{"id":848,"date":"2013-03-11T00:30:19","date_gmt":"2013-03-11T02:30:19","guid":{"rendered":"http:\/\/www.encontrajandira.com.br\/noticias\/?p=848"},"modified":"2013-08-14T22:14:27","modified_gmt":"2013-08-15T00:14:27","slug":"operacao-aquiles-coloca-66-pessoas-atras-das-grades-em-jandira-e-regiao","status":"publish","type":"post","link":"https:\/\/www.encontrajandira.com.br\/noticias\/operacao-aquiles-coloca-66-pessoas-atras-das-grades-em-jandira-e-regiao\/","title":{"rendered":"Opera\u00e7\u00e3o Aquiles coloca 66 pessoas atr\u00e1s das grades em Jandira e regi\u00e3o"},"content":{"rendered":"<p>Policiais civis da Delegacia Seccional de Carapicu\u00edba deflagraram no \u00faltimo final de semana, 2 e 3 de mar\u00e7o, a Opera\u00e7\u00e3o Aquiles que teve como objetivo o combate ao tr\u00e1fico de drogas, jogos de azar, recupera\u00e7\u00e3o e apreens\u00e3o de objetos il\u00edcitos, al\u00e9m do cumprimento de mandados de busca, apreens\u00e3o e pris\u00e3o. A Opera\u00e7\u00e3o resultou na pris\u00e3o de 66 pessoas e nas apreens\u00f5es de 185 ve\u00edculos da cidade de Jandira e regi\u00e3o, 12.400 artigos de pirataria e 3,4 kg de entorpecentes.<\/p>\n<p>Cerca de 140 policiais das unidades policiais localizadas nos oito munic\u00edpios que integram a Seccional &#8211; cidade de Carapicu\u00edba, Barueri, Jandira, Itapevi, Santana de Parna\u00edba, Pirapora do Bom Jesus, Cotia e Vargem Grande Paulista \u2013 participaram da Opera\u00e7\u00e3o.<\/p>\n<p><em>Fonte: WEB Di\u00e1rio<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais civis da Delegacia Seccional de Carapicu\u00edba deflagraram no \u00faltimo final de semana, 2 e 3 de mar\u00e7o, a Opera\u00e7\u00e3o Aquiles que teve como objetivo o combate ao tr\u00e1fico de drogas, jogos de azar, recupera\u00e7\u00e3o e apreens\u00e3o de objetos il\u00edcitos, al\u00e9m do cumprimento de mandados de busca, apreens\u00e3o e pris\u00e3o. A Opera\u00e7\u00e3o resultou na pris\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"_links":{"self":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/848"}],"collection":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=848"}],"version-history":[{"count":3,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/848\/revisions"}],"predecessor-version":[{"id":1490,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/848\/revisions\/1490"}],"wp:attachment":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}