{"id":519,"date":"2012-06-13T00:01:12","date_gmt":"2012-06-13T02:01:12","guid":{"rendered":"http:\/\/www.encontrajandira.com.br\/noticias\/?p=519"},"modified":"2013-08-14T22:14:24","modified_gmt":"2013-08-15T00:14:24","slug":"prefeitura-de-jandira-e-multada-em-r50-milhoes-pelo-ministerio-publico","status":"publish","type":"post","link":"https:\/\/www.encontrajandira.com.br\/noticias\/prefeitura-de-jandira-e-multada-em-r50-milhoes-pelo-ministerio-publico\/","title":{"rendered":"Prefeitura de Jandira \u00e9 multada em R$50 milh\u00f5es pelo Minist\u00e9rio P\u00fablico"},"content":{"rendered":"<p>\u00a0Prefeitura de Jandira foi multada, pelo Minist\u00e9rio P\u00fablico (MP), em R$50 milh\u00f5es pelo descumprimento de um Termo de Ajustamento de Conduta (TAC), firmado em maio do ano passado, prevendo a amplia\u00e7\u00e3o de vagas nas creches da rede municipal de ensino.<\/p>\n<p>Essa puni\u00e7\u00e3o teve repercuss\u00e3o na <a title=\"C\u00e2mara Municipal de Jandira\" href=\"http:\/\/www.encontrajandira.com.br\/jandira\/camara-municipal-de-jandira.shtml\" target=\"_blank\">C\u00e2mara Municipal de Jandira <\/a>e durante a sess\u00e3o de ontem. O presidente da Casa, vereador Wesley Teixeira (PSC), informou que, com base nessa decis\u00e3o do MP, o Poder Legislativo pode pedir novamente o afastamento da prefeita Anabel Sabatine (PSDB) por improbidade administrativa.<\/p>\n<p>Segundo ele, a vota\u00e7\u00e3o j\u00e1 poderia ter sido feita na sess\u00e3o na \u00faltima\u00a0ter\u00e7a-feira, dia 12, mas foi adiada. &#8220;N\u00e3o coloquei em pauta para que todos vereadores possam analisar o documento. Podemos convocar uma sess\u00e3o extraordin\u00e1ria ou discutir esse assunto na pr\u00f3xima sess\u00e3o. Vamos decidir juntos como a C\u00e2mara ir\u00e1 se posicionar diante dessa not\u00edcia do Minist\u00e9rio P\u00fablico&#8221;, disse.<\/p>\n<p>Conforme publicado no site do MP, o TAC, assinado pelo promotor de Justi\u00e7a Jos\u00e9 Augusto de Barros Faro e a prefeitura Anabel, previa a cria\u00e7\u00e3o paulatina de vagas em creches municipais. Um total de 700 vagas j\u00e1 deveriam ter sido abertas, sendo 600 em novembro de 2011 e outras 100 em maio de 2012. Al\u00e9m disso, a administra\u00e7\u00e3o municipal deveria zerar a demanda at\u00e9 maio de 2013.<\/p>\n<p>Mas, ao acompanhar o andamento do cumprimento da primeira etapa do TAC, o MP constatou que at\u00e9 abril nenhuma vaga foi formalmente criada pela prefeitura. &#8220;Diante desse quadro, a Promotoria ingressou, no \u00faltimo dia 16, com a\u00e7\u00e3o de execu\u00e7\u00e3o da multa prevista no acordo&#8221;, informou o Minist\u00e9rio P\u00fablico.<\/p>\n<p>Wesley tamb\u00e9m contou que a den\u00fancia sobre o descumprimento do TAC chegou at\u00e9 a C\u00e2mara pelo mun\u00edcipe Jos\u00e9 Carlos Feitosa. &#8220;O morador da cidade encaminhou uma den\u00fancia para a C\u00e2mara e pediu para o Legislativo se posicionar diante do fato. Como presidente da Casa, encaminhei a den\u00fancia para o Jur\u00eddico da C\u00e2mara avaliar o pedido&#8221;, concluiu.<\/p>\n<p>De acordo com o presidente, o l\u00edder da prefeita na C\u00e2mara (Gerson Cerqueira \u2013 PTN) disse ter um documento que prova que esse assunto j\u00e1 est\u00e1 resolvido junto ao MP. &#8220;Vamos esperar o vereador ler esse documento. Se o TAC estiver concluso n\u00e3o temos motivos para pedir o afastamento da prefeita&#8221;, disse Wesley.<\/p>\n<p>A reportagem de <em>O Di\u00e1rio<\/em> entrou em contato com a Secretaria de Comunica\u00e7\u00e3o da <a href=\"http:\/\/www.encontrajandira.com.br\/jandira\/prefeitura-de-jandira.shtml\" target=\"_blank\">Prefeitura de Jandira<\/a> mas, at\u00e9 o fechamento desta edi\u00e7\u00e3o, n\u00e3o obteve resposta sobre o caso.<\/p>\n<p>Wesley \u2013 \u201cVamos decidir juntos como a C\u00e2mara ir\u00e1 se posicionar diante dessa not\u00edcia do Minist\u00e9rio P\u00fablico&#8221;<\/p>\n<p><em>Fonte: WEB Di\u00e1rio<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Prefeitura de Jandira foi multada, pelo Minist\u00e9rio P\u00fablico (MP), em R$50 milh\u00f5es pelo descumprimento de um Termo de Ajustamento de Conduta (TAC), firmado em maio do ano passado, prevendo a amplia\u00e7\u00e3o de vagas nas creches da rede municipal de ensino. Essa puni\u00e7\u00e3o teve repercuss\u00e3o na C\u00e2mara Municipal de Jandira e durante a sess\u00e3o de ontem. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519"}],"collection":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=519"}],"version-history":[{"count":2,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519\/revisions"}],"predecessor-version":[{"id":1408,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/519\/revisions\/1408"}],"wp:attachment":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}