{"id":42,"date":"2011-07-19T16:36:42","date_gmt":"2011-07-19T18:36:42","guid":{"rendered":"http:\/\/www.encontrajandira.com.br\/noticias\/?p=42"},"modified":"2013-08-14T22:14:05","modified_gmt":"2013-08-15T00:14:05","slug":"gcm-de-jandira-completa-13-anos-de-trabalho","status":"publish","type":"post","link":"https:\/\/www.encontrajandira.com.br\/noticias\/gcm-de-jandira-completa-13-anos-de-trabalho\/","title":{"rendered":"GCM de Jandira completa 13 anos de trabalho"},"content":{"rendered":"<p>A GCM da cidade Jandira iniciou no \u00faltimo dia 11 o curso de capacita\u00e7\u00e3o e aperfei\u00e7oamento do seu efetivo, inicialmente come\u00e7ou uma turma de 18 GCMs, a meta \u00e9 capacitar e treinar toda a corpora\u00e7\u00e3o. Dentro da grade do curso foi ministrado aulas com os seguintes temas: Gerenciamento de crises e negocia\u00e7\u00e3o com ref\u00e9ns, sobreviv\u00eancia policial, preven\u00e7\u00e3o ao uso indevido de drogas, condu\u00e7\u00e3o de viaturas e dire\u00e7\u00e3o evasiva, conduta e postura profissional, conceito de t\u00e9cnicas operacionais, progress\u00e3o em local de alto risco e manuseio de armamento.<\/p>\n<p>Na mesma semana que iniciou o curso foi comemorado no dia 13 de julho o \u201cDia municipal do Guarda Civil\u201d a data faz parte do calend\u00e1rio oficial do munic\u00edpio e \u00e9 comemorado todo ano. A GCM de Jandira completou 13 anos de exist\u00eancia e servi\u00e7os prestados a popula\u00e7\u00e3o. O pronto atendimento da GCM vai desde uma simples averigua\u00e7\u00e3o at\u00e9 a pris\u00e3o de acusados de tr\u00e1fico de entorpecentes, assaltantes, estelionat\u00e1rios, al\u00e9m de indiv\u00edduos procurados e foragidos da justi\u00e7a.<\/p>\n<p>Durante a semana do curso de capacita\u00e7\u00e3o, outra turma da guarda tamb\u00e9m deu in\u00edcio a um novo curso, pilotagem de motocicletas na CET, segundo o comando da Guarda Civil a inten\u00e7\u00e3o \u00e9 qualificar e ter o maior n\u00famero poss\u00edvel de integrantes participando de algum tipo de curso e treinamento.<\/p>\n<p>\u201cA Guarda Municipal de Jandira tem procurado melhorar, a cada dia, sua forma de atua\u00e7\u00e3o, seus m\u00e9todos e seus procedimentos durante o servi\u00e7o de patrulhamento preventivo. O esfor\u00e7o em atender a popula\u00e7\u00e3o \u00e9 constante, s\u00e3o 13 anos de muito trabalho, com um \u00fanico objetivo, atender os anseios da popula\u00e7\u00e3o jandirense\u201d. Comentou o Sub. Comte. Cl\u00f3vis Castro.<\/p>\n<p>\u201cInvestir em seguran\u00e7a \u00e9 se preocupar com o futuro da popula\u00e7\u00e3o jandirense \u00e9 cuidar das nossas crian\u00e7as e do cidad\u00e3o de bem. N\u00e3o podemos nunca deixar de ter esse cuidado com o povo, e esse \u00e9 o nosso papel, pensar num futuro melhor e trabalhar para que isso aconte\u00e7a\u201d, declarou Dra. Anabel.<\/p>\n<p><em>Fonte: Folha de Jandira<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A GCM da cidade Jandira iniciou no \u00faltimo dia 11 o curso de capacita\u00e7\u00e3o e aperfei\u00e7oamento do seu efetivo, inicialmente come\u00e7ou uma turma de 18 GCMs, a meta \u00e9 capacitar e treinar toda a corpora\u00e7\u00e3o. Dentro da grade do curso foi ministrado aulas com os seguintes temas: Gerenciamento de crises e negocia\u00e7\u00e3o com ref\u00e9ns, sobreviv\u00eancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"_links":{"self":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/42"}],"collection":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":2,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"predecessor-version":[{"id":1048,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/42\/revisions\/1048"}],"wp:attachment":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}