{"id":295,"date":"2012-01-12T10:59:03","date_gmt":"2012-01-12T12:59:03","guid":{"rendered":"http:\/\/www.encontrajandira.com.br\/noticias\/?p=295"},"modified":"2013-08-14T22:14:19","modified_gmt":"2013-08-15T00:14:19","slug":"jandira-se-prepara-para-o-combate-a-dengue-no-verao","status":"publish","type":"post","link":"https:\/\/www.encontrajandira.com.br\/noticias\/jandira-se-prepara-para-o-combate-a-dengue-no-verao\/","title":{"rendered":"Jandira se prepara para o combate \u00e0 dengue no ver\u00e3o"},"content":{"rendered":"<p>O\u00a0ver\u00e3o\u00a0chegou e com ele o per\u00edodo de chuvas, o que preocupa os mun\u00edcipes e os agentes de sa\u00fade devido ao aumento do ac\u00famulo de \u00e1gua, o que causa a prolifera\u00e7\u00e3o do mosquito aedes aegypti. Mas a cidade de Jandira j\u00e1 se prepara para o combate ao mosquito da dengue.<\/p>\n<p>No ano de 2011, Jandira confirmou 31 casos de dengue, os bairros mais atingidos foram Alvorada, Jardim Mar\u00edlia e Vale do\u00a0Sol. Para este ano, a coordenadora da vigil\u00e2ncia em sa\u00fade \u2013 Ana Cl\u00e1udia Oliveira, afirmou que o\u00a0trabalho\u00a0ser\u00e1 intensificado nesses bairros, al\u00e9m de uma nova capacita\u00e7\u00e3o para os m\u00e9dicos que enfermeiros que atender\u00e3o casos de dengue.<\/p>\n<p>A coordenadora salientou ainda que no dia 16 de janeiro, come\u00e7ar\u00e1 um trabalho de integra\u00e7\u00e3o com os agentes comunit\u00e1rios de\u00a0sa\u00fade\u00a0para a\u00e7\u00f5es no combate a dengue nos bairros. \u201cAgora s\u00e3o mais pessoas trabalhando na sa\u00fade para o combate\u201d.<\/p>\n<p><strong><em>Preven\u00e7\u00e3o<\/em><\/strong><\/p>\n<p>A melhor forma de se evitar a dengue \u00e9 combater os focos de ac\u00famulo de \u00e1gua, locais prop\u00edcios para a cria\u00e7\u00e3o do mosquito transmissor da doen\u00e7a. Para isso, \u00e9 importante n\u00e3o acumular \u00e1gua em latas, embalagens, copos pl\u00e1sticos, tampinhas de refrigerantes, pneus velhos, vasinhos de plantas, jarros de flores, garrafas, caixas d \u00e1gua, tambores, lat\u00f5es, cisternas, sacos pl\u00e1sticos e lixeiras, entre outros.<\/p>\n<p><em>Fonte: Folha de Jandira<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0ver\u00e3o\u00a0chegou e com ele o per\u00edodo de chuvas, o que preocupa os mun\u00edcipes e os agentes de sa\u00fade devido ao aumento do ac\u00famulo de \u00e1gua, o que causa a prolifera\u00e7\u00e3o do mosquito aedes aegypti. Mas a cidade de Jandira j\u00e1 se prepara para o combate ao mosquito da dengue. No ano de 2011, Jandira confirmou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"_links":{"self":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/295"}],"collection":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":3,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/295\/revisions"}],"predecessor-version":[{"id":1301,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/posts\/295\/revisions\/1301"}],"wp:attachment":[{"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrajandira.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}